{"id":195,"count":4,"description":"","link":"https:\/\/www.nlis.com\/blog\/category\/lincolnshire-county-council\/","name":"Lincolnshire County Council","slug":"lincolnshire-county-council","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/categories\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/posts?categories=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}