{"id":2504,"count":2,"description":"","link":"https:\/\/www.nlis.com\/blog\/category\/groundsure-homebuyers\/","name":"Groundsure Homebuyers","slug":"groundsure-homebuyers","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/categories\/2504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.nlis.com\/blog\/wp-json\/wp\/v2\/posts?categories=2504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}